{"id":5373,"date":"2024-04-08T18:34:00","date_gmt":"2024-04-08T16:34:00","guid":{"rendered":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/?p=5373"},"modified":"2024-10-22T16:13:20","modified_gmt":"2024-10-22T14:13:20","slug":"robo-casa-vivienda-cobertura-seguro","status":"publish","type":"post","link":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/","title":{"rendered":"\u00bfC\u00f3mo debes actuar si sufres un robo en casa?"},"content":{"rendered":"\n<p>La primera preocupaci\u00f3n de los espa\u00f1oles relacionada con el hogar son los <strong>robos en casa<\/strong>, seguido de la <strong>ocupaci\u00f3n<\/strong> y<strong> los incendios<\/strong>. Cada temporada de vacaciones se producen miles de asaltos a viviendas. La prevenci\u00f3n es la mejor medida de seguridad.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo conviene actuar si hay un robo en la casa? <\/strong>Te han robado en casa y no tienes facturas, \u00bfqu\u00e9 debes hacer? \u00bfSi entran en mi casa puedo defenderme?<\/p>\n\n\n\n<p>Te contamos todo sobre los robos en viviendas en Espa\u00f1a y las mejores recomendaciones si sufres uno.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_58 counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<p class=\"ez-toc-title\">&Iacute;ndice<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a047da6a7e34\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #ffffff;color:#ffffff\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #ffffff;color:#ffffff\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a047da6a7e34\" checked aria-label=\"Toggle\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#La_ciencia_del_robo_en_casa_%C2%BFComo_actuan_los_delincuentes\" title=\"La ciencia del robo en casa: \u00bfC\u00f3mo act\u00faan los delincuentes?\">La ciencia del robo en casa: \u00bfC\u00f3mo act\u00faan los delincuentes?<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#%C2%BFComo_roban_en_casa\" title=\"\u00bfC\u00f3mo roban en casa?&nbsp;\">\u00bfC\u00f3mo roban en casa?&nbsp;<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Robo_en_casa_%C2%BFComo_actuar\" title=\"Robo en casa: \u00bfC\u00f3mo actuar?\">Robo en casa: \u00bfC\u00f3mo actuar?<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#1_Llama_a_la_Policia\" title=\"1. Llama a la Polic\u00eda\">1. Llama a la Polic\u00eda<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#2_Fotografia_el_estado_de_la_vivienda\" title=\"2. Fotograf\u00eda el estado de la vivienda\">2. Fotograf\u00eda el estado de la vivienda<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#3_Comprueba_si_faltan_objetos_de_valor\" title=\"3. Comprueba si faltan objetos de valor\">3. Comprueba si faltan objetos de valor<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#4_Pon_una_denuncia\" title=\"4. Pon una denuncia\">4. Pon una denuncia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#5_Recupera_las_facturas\" title=\"5. Recupera las facturas\">5. Recupera las facturas<\/a><ul class='ez-toc-list-level-4'><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Me_han_robado_en_casa_y_no_tengo_facturas_%C2%BFQue_hago\" title=\"Me han robado en casa y no tengo facturas: \u00bfQu\u00e9 hago?\">Me han robado en casa y no tengo facturas: \u00bfQu\u00e9 hago?<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#6_Contacta_con_tu_aseguradora\" title=\"6. Contacta con tu aseguradora\">6. Contacta con tu aseguradora<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#%C2%BFQue_hacer_si_roban_en_casa_y_estoy_dentro\" title=\"\u00bfQu\u00e9 hacer si roban en casa y estoy dentro?\">\u00bfQu\u00e9 hacer si roban en casa y estoy dentro?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#%C2%BFComo_proteger_tu_vivienda_frente_a_robos_en_casa\" title=\"\u00bfC\u00f3mo proteger tu vivienda frente a robos en casa?\">\u00bfC\u00f3mo proteger tu vivienda frente a robos en casa?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Me_han_robado_en_casa_%C2%BFQue_cubre_el_seguro\" title=\"Me han robado en casa. \u00bfQu\u00e9 cubre el seguro?\">Me han robado en casa. \u00bfQu\u00e9 cubre el seguro?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Preguntas_frecuentes\" title=\"Preguntas frecuentes\">Preguntas frecuentes<\/a><ul class='ez-toc-list-level-3'><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Como_pillar_a_alguien_que_te_ha_robado\" title=\"C\u00f3mo pillar a alguien que te ha robado\">C\u00f3mo pillar a alguien que te ha robado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#%C2%BFSi_entran_en_mi_casa_puedo_defenderme\" title=\"\u00bfSi entran en mi casa puedo defenderme?\">\u00bfSi entran en mi casa puedo defenderme?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Me_han_robado_en_casa_sin_forzar_la_cerradura\" title=\"Me han robado en casa sin forzar la cerradura\">Me han robado en casa sin forzar la cerradura<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#Sonar_que_te_roban_en_casa_contigo_dentro\" title=\"So\u00f1ar que te roban en casa contigo dentro\">So\u00f1ar que te roban en casa contigo dentro<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"La_ciencia_del_robo_en_casa_%C2%BFComo_actuan_los_delincuentes\"><\/span><strong>La ciencia del robo en casa: \u00bfC\u00f3mo act\u00faan los delincuentes?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En los \u00faltimos a\u00f1os han proliferado bandas organizadas especializadas en los asaltos a viviendas. Cada vez son m\u00e1s expertos, sigilosos y r\u00e1pidos a la hora de hacerse con un bot\u00edn. Sin embargo, cada vez conocemos con m\u00e1s detalle c\u00f3mo operan y las t\u00e9cnicas de asalto que usan.<\/p>\n\n\n\n<p>Los <strong>chalets y las villas son el tipo de vivienda m\u00e1s asaltada<\/strong> en Espa\u00f1a. En concreto, sufren un 50% m\u00e1s de intrusiones que los pisos y un 19% m\u00e1s que los pareados o adosados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_roban_en_casa\"><\/span>\u00bfC\u00f3mo roban en casa?&nbsp;<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Has de saber que existen unas franjas horarias que concentran muchos m\u00e1s asaltos. <strong>La mayor\u00eda de robos se producen los viernes y los s\u00e1bados<\/strong>. El horario preferido para los asaltantes es <strong>entre las 19:00 y las 23:00<\/strong>. Aunque resulte llamativo, es una franja t\u00edpica donde la vivienda suele estar vac\u00eda.<\/p>\n\n\n\n<p>Adem\u00e1s, el <strong>domingo es el d\u00eda de la semana que menos robos se registran<\/strong> en las casas. Y lejos de lo que puede pensar la mayor\u00eda de personas, los <strong>robos en viviendas durante la madrugada son residuales<\/strong>.<\/p>\n\n\n\n<p>Por otro lado, <strong>los<\/strong> <strong>d\u00edas festivos aumentan un 25% las probabilidades <\/strong>de sufrir un robo que cualquier otro d\u00eda laboral. Si observamos la geograf\u00eda espa\u00f1ola, Andaluc\u00eda, Comunidad Valenciana, Islas Baleares y Pa\u00eds Vasco son las comunidades donde existe m\u00e1s riesgo de intrusi\u00f3n.<\/p>\n\n\n\n<p>\u2705<strong> \u00a1Dato curioso! <\/strong>Las viviendas ubicadas en plazas y avenidas registran m\u00e1s intrusiones que las que se encuentran en urbanizaciones o fincas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Robo_en_casa_%C2%BFComo_actuar\"><\/span><strong>Robo en casa: \u00bfC\u00f3mo actuar?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Llegas a casa y te encuentras la vivienda patas arriba. No hay duda: <strong><em>me han robado en casa, \u00bfqu\u00e9 hago?<\/em> <\/strong>As\u00ed deber\u00edas actuar.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Llama_a_la_Policia\"><\/span>1. Llama a la Polic\u00eda<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La primera reacci\u00f3n cuando descubres que te han robado en casa posiblemente sea recorrer todas las habitaciones para descubrir la magnitud de la intrusi\u00f3n. Sin embargo <strong>los asaltantes podr\u00edan estar todav\u00eda en el interior <\/strong>de la vivienda.<\/p>\n\n\n\n<p><strong>Llama siempre a la Polic\u00eda <\/strong>y deja <strong>que sean ellos los que inspeccionen la casa<\/strong>. Te recomendamos que les esperes siempre fuera de la vivienda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Fotografia_el_estado_de_la_vivienda\"><\/span>2. Fotograf\u00eda el estado de la vivienda<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Es posible que tu casa est\u00e9 patas arriba: ropa por el suelo, el contenido de los cajones por encima de la cama y mucha desorganizaci\u00f3n en general. Aun as\u00ed, evita ordenar la casa.<\/p>\n\n\n\n<p><strong>Aseg\u00farate de fotografiar cada detalle del robo en el hogar<\/strong>. Podr\u00eda servir como una prueba esencial en caso de denuncia o reclamaci\u00f3n a tu aseguradora.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Comprueba_si_faltan_objetos_de_valor\"><\/span>3. Comprueba si faltan objetos de valor<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Ya sea dinero en efectivo, joyas, alg\u00fan cuadro de valor o bolsos caros\u2026 <strong>Haz un inventario <\/strong>de todo aquello que se han llevado.<\/p>\n\n\n\n<p><strong>\u25b7<\/strong> <strong>\u00a1Esto te interesa! <\/strong><a title=\"5 elementos que mejorar\u00e1n la comodidad de tu hogar\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/comodidad-hogar-domotica-inteligente-digital\/\" target=\"_blank\" rel=\"noopener\">5 elementos que mejorar\u00e1n la comodidad de tu hogar<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Pon_una_denuncia\"><\/span>4. Pon una denuncia<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Este paso es imprescindible. <strong>El robo en casa habitada debes denunciarlo siempre<\/strong>. Tendr\u00e1s que adjuntar la denuncia en la reclamaci\u00f3n que hagas a tu aseguradora.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Recupera_las_facturas\"><\/span>5. Recupera las facturas<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>A la hora de reclamar a tu aseguradora, contar con todas las facturas de los objetos sustra\u00eddos facilitar\u00e1 la gesti\u00f3n. Te recomendamos que <strong>recuperes todos los tickets de compra que puedas<\/strong> y los incluyas en el parte.<\/p>\n\n\n\n<p>A la hora de reclamar a la aseguradora los objetos sustra\u00eddos en un robo en casa, <strong>aportar las facturas ayuda como elemento probatorio<\/strong> de su valor y preexistencia.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Me_han_robado_en_casa_y_no_tengo_facturas_%C2%BFQue_hago\"><\/span>Me han robado en casa y no tengo facturas: \u00bfQu\u00e9 hago?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n\n\n<p>En estos casos cuanta mas documentaci\u00f3n aportes a la aseguradora mejor y m\u00e1s r\u00e1pido ser\u00e1 el tr\u00e1mite del siniestro. Revisa tu correo electr\u00f3nico en busca de<strong> facturas online<\/strong>. Las fotograf\u00edas del objeto tambi\u00e9n pueden ayudarte.<\/p>\n\n\n\n<p>\u25b7 <strong>Antes de continuar, te interesa est\u00e9 art\u00edculo:<\/strong> <a title=\"\u00bfTus contrase\u00f1as son realmente seguras?\" href=\"https:\/\/www.generali.es\/blog\/generalimasqueseguros\/proteger-movil-hackers\/\" target=\"_blank\" rel=\"noopener\">\u00bfTus contrase\u00f1as son realmente seguras?<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_Contacta_con_tu_aseguradora\"><\/span>6. Contacta con tu aseguradora<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Una vez tengas toda la documentaci\u00f3n, <strong>contacta con tu aseguradora para dar un parte de robo en casa<\/strong>. Recuerda adjuntar todas las facturas, inventario y fotograf\u00edas que describan los objetos sustra\u00eddos.<\/p>\n\n\n\n<p>En <strong>GENERALI<\/strong> contamos con una oferta de <a title=\"Seguro de Hogar\" href=\"https:\/\/www.generali.es\/seguros-particulares\/hogar\" target=\"_blank\" rel=\"noopener\">Seguros de Hogar<\/a> que <strong>se adapta a tus necesidades, y que podr\u00e1s configurar a tu medida<\/strong>. Protege tu vivienda con las mejores coberturas. <a title=\"Cons\u00faltanos\" href=\"https:\/\/www.generali.es\/static\/MKT\/seguro-hogar\/\" target=\"_blank\" rel=\"noopener\">Cons\u00faltanos<\/a> sin compromiso.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFQue_hacer_si_roban_en_casa_y_estoy_dentro\"><\/span><strong>\u00bfQu\u00e9 hacer si roban en casa y estoy dentro?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>En caso de sufrir un robo en casa estando dentro la prioridad debe ser tu integridad f\u00edsica. No merece la pena proteger los objetos f\u00edsicos. Si esto te ocurre, act\u00faa as\u00ed:<\/p>\n\n\n\n<ol>\n<li><strong>Haz ruido y enciende las luces<\/strong> de la vivienda. Normalmente los ladrones no suelen arriesgarse a robar en viviendas con los due\u00f1os dentro. Hazles saber que est\u00e1is en casa.<\/li>\n\n\n\n<li><strong>Enci\u00e9rrate en la habitaci\u00f3n m\u00e1s inaccesible<\/strong> de la casa y echa el pestillo.<\/li>\n\n\n\n<li><strong>Llama a la Polic\u00eda<\/strong>.<\/li>\n\n\n\n<li>Si tienes un sistema de seguridad <strong>con bot\u00f3n SOS, p\u00falsalo<\/strong>. La Central Receptora de Alarmas se encargar\u00e1 de visualizar las im\u00e1genes del interior y ofrecer informaci\u00f3n a las fuerzas de seguridad.<\/li>\n\n\n\n<li><strong>Evita la confrontaci\u00f3n con los ladrones<\/strong>. Haz todo aquello que te ordenen. No pongas en riesgo tu seguridad.<\/li>\n\n\n\n<li><strong>Mant\u00e9n la calma<\/strong>. Recuerda que los ladrones solo quieren los objetos de valor.<\/li>\n<\/ol>\n\n\n\n<p>\u25b7 <strong>\u00a1Te interesa! <\/strong><a href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/cerradura-electronica\/\" target=\"_blank\" rel=\"noopener\">Cerradura electr\u00f3nica: ventajas e inconvenientes<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFComo_proteger_tu_vivienda_frente_a_robos_en_casa\"><\/span><strong>\u00bfC\u00f3mo proteger tu vivienda frente a robos en casa?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La mejor manera de prevenir un asalto en casa es reforzar la seguridad en los accesos de las puertas y ventanas. Echa un vistazo a este v\u00eddeo y <strong>evita un robo en casa siguiendo los consejos<\/strong>.<\/p>\n\n\n\n<p><video preload=\"none\" controls=\"controls\" width=\"100%\" height=\"150\"><source src=\"https:\/\/qbxriz.files.cmp.optimizely.com\/download\/b0cb13a6ef6711ee9be03ad19fc40bf6\">Your browser doesn&#8217;t support the HTML5 video tag.<\/video><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Me_han_robado_en_casa_%C2%BFQue_cubre_el_seguro\"><\/span><strong>Me han robado en casa. \u00bfQu\u00e9 cubre el seguro?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La cobertura de tu seguro depender\u00e1 del tipo de seguro que hayas contratado. Aun as\u00ed, podemos distinguir dos coberturas comunes:<\/p>\n\n\n\n<ul>\n<li><strong>Coberturas del continente<\/strong>. Solo cubren los da\u00f1os que se producen en la vivienda durante el robo. Esto significa que solo cubren cristales rotos, la cerradura de la puerta da\u00f1ada o cualquier desperfecto que afecte a los elementos estructurales de vivienda.<\/li>\n\n\n\n<li><strong>Coberturas del contenido<\/strong>. \u00c9sta cubre el mobiliario y objetos del interior de la vivienda. La compa\u00f1\u00eda te indemnizar\u00e1 por aquellos objetos sustra\u00eddos.<\/li>\n<\/ul>\n\n\n\n<p>\u2705<strong>\u00a1Consejo! <\/strong>La mejor forma de protegerte en caso de robo en casa es una seguro que incluya ambas coberturas. Te recomendamos que cuando lo contrates, realices una declaraci\u00f3n expresa de aquellos objetos que deseas asegurar.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Preguntas_frecuentes\"><\/span><strong>Preguntas frecuentes<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_pillar_a_alguien_que_te_ha_robado\"><\/span>C\u00f3mo pillar a alguien que te ha robado<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>Instala un sistema de videovigilancia en tu casa <\/strong>para supervisar todo lo que ocurre en ella. Algunas c\u00e1maras de v\u00eddeo control permiten <strong>visualizar en directo <\/strong>tu vivienda a trav\u00e9s de una app para sorprender a quien te est\u00e9 robando.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFSi_entran_en_mi_casa_puedo_defenderme\"><\/span>\u00bfSi entran en mi casa puedo defenderme?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>La legislaci\u00f3n actual <strong>no prev\u00e9 el derecho a defenderse si entran en tu propia casa<\/strong>, pero s\u00ed la llamada <strong>leg\u00edtima defensa<\/strong>. Su aplicaci\u00f3n puede exonerar de una responsabilidad criminal o reducir la pena en caso de haber cometido un delito.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Me_han_robado_en_casa_sin_forzar_la_cerradura\"><\/span>Me han robado en casa sin forzar la cerradura<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Los intrusos m\u00e1s h\u00e1biles son capaces de vulnerar una cerradura sin llegar a forzarla con <strong>t\u00e9cnicas como el ganzuado, el impresioning o el bumping<\/strong>. Para evitarlo instala una puerta blindada o acorazada en casa.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sonar_que_te_roban_en_casa_contigo_dentro\"><\/span>So\u00f1ar que te roban en casa contigo dentro<span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p><strong>So\u00f1ar que te roban en casa significa que algo o alguien est\u00e1 afectando a tu paz interior<\/strong>. Se entiende tu casa como el hogar que te pertenece y quien intente atentar contra ella provocar\u00e1 esa perturbaci\u00f3n o conflicto interno en tu vida.<\/p>\n\n\n\n<p>Para disfrutar con tranquilidad de tu vivienda en todas las \u00e9pocas merece la pena tener un <a title=\"Seguro de Hogar\" href=\"https:\/\/www.generali.es\/seguros-particulares\/hogar\" target=\"_blank\" rel=\"noopener\"><strong>Seguro de Hogar<\/strong><\/a><strong> completo y que responda con eficacia cuando lo necesites<\/strong>. En <strong>GENERALI<\/strong> ofrecemos amplias coberturas ante robo, vandalismo, inundaciones, incendios, fen\u00f3menos meteorol\u00f3gicos, roturas o da\u00f1os el\u00e9ctricos.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/pixel.welcomesoftware.com\/px.gif?key=YXJ0aWNsZT1mNDZmOWU2ZWRmMGYxMWVlODE2YzI2N2M1NTQ1YThkMA==\" alt=\"\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La primera preocupaci\u00f3n de los espa\u00f1oles relacionada con el hogar son los robos en casa, seguido de la ocupaci\u00f3n y los incendios. Cada temporada de vacaciones se producen miles de asaltos a viviendas. La prevenci\u00f3n es la mejor medida de seguridad. \u00bfC\u00f3mo conviene actuar si hay un robo en la casa? Te han robado en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5372,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u25b7 \u00bfQu\u00e9 hacer si sufres un robo en casa? 6 formas de actuar<\/title>\n<meta name=\"description\" content=\"\ud83c\udfe0 El robo en casa est\u00e1n a la orden del d\u00eda. Hay que estar PREPARADO si sufres uno. \u279c Pon en pr\u00e1ctica estas \ud83d\udc466 medidas si asaltan tu vivienda\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipo GENERALI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/\"},\"author\":{\"name\":\"Equipo GENERALI\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/person\/b3e3621e80b273ef3366c6dc945ab47e\"},\"headline\":\"\u00bfC\u00f3mo debes actuar si sufres un robo en casa?\",\"datePublished\":\"2024-04-08T16:34:00+00:00\",\"dateModified\":\"2024-10-22T14:13:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/\"},\"wordCount\":1438,\"publisher\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#organization\"},\"articleSection\":[\"Seguridad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/\",\"url\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/\",\"name\":\"\u25b7 \u00bfQu\u00e9 hacer si sufres un robo en casa? 6 formas de actuar\",\"isPartOf\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#website\"},\"datePublished\":\"2024-04-08T16:34:00+00:00\",\"dateModified\":\"2024-10-22T14:13:20+00:00\",\"description\":\"\ud83c\udfe0 El robo en casa est\u00e1n a la orden del d\u00eda. Hay que estar PREPARADO si sufres uno. \u279c Pon en pr\u00e1ctica estas \ud83d\udc466 medidas si asaltan tu vivienda\",\"breadcrumb\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Seguridad\",\"item\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/seguridad\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfC\u00f3mo debes actuar si sufres un robo en casa?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#website\",\"url\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/\",\"name\":\"Tu Asesor de Hogar\",\"description\":\"Blog de Hogar de GENERALI\",\"publisher\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#organization\",\"name\":\"Tu Asesor de Hogar\",\"url\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2021\/04\/generali.png\",\"contentUrl\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2021\/04\/generali.png\",\"width\":100,\"height\":81,\"caption\":\"Tu Asesor de Hogar\"},\"image\":{\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/person\/b3e3621e80b273ef3366c6dc945ab47e\",\"name\":\"Equipo GENERALI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2020\/11\/equipo_generali-150x150.jpg\",\"contentUrl\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2020\/11\/equipo_generali-150x150.jpg\",\"caption\":\"Equipo GENERALI\"},\"description\":\"El equipo de Tu Asesor Hogar est\u00e1 compuesto por especialistas en la seguridad, el bricolaje y ahorro en el hogar, as\u00ed como profesionales t\u00e9cnicos de los seguros de hogar. Te ayudamos a que tengas una vida m\u00e1s segura y tranquila y te ofrecemos contenido \u00fatil para tu d\u00eda a d\u00eda.\",\"url\":\"https:\/\/www.generali.es\/blog\/tuasesorhogar\/author\/generali_asesor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u25b7 \u00bfQu\u00e9 hacer si sufres un robo en casa? 6 formas de actuar","description":"\ud83c\udfe0 El robo en casa est\u00e1n a la orden del d\u00eda. Hay que estar PREPARADO si sufres uno. \u279c Pon en pr\u00e1ctica estas \ud83d\udc466 medidas si asaltan tu vivienda","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/","twitter_misc":{"Escrito por":"Equipo GENERALI","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#article","isPartOf":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/"},"author":{"name":"Equipo GENERALI","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/person\/b3e3621e80b273ef3366c6dc945ab47e"},"headline":"\u00bfC\u00f3mo debes actuar si sufres un robo en casa?","datePublished":"2024-04-08T16:34:00+00:00","dateModified":"2024-10-22T14:13:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/"},"wordCount":1438,"publisher":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#organization"},"articleSection":["Seguridad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/","url":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/","name":"\u25b7 \u00bfQu\u00e9 hacer si sufres un robo en casa? 6 formas de actuar","isPartOf":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#website"},"datePublished":"2024-04-08T16:34:00+00:00","dateModified":"2024-10-22T14:13:20+00:00","description":"\ud83c\udfe0 El robo en casa est\u00e1n a la orden del d\u00eda. Hay que estar PREPARADO si sufres uno. \u279c Pon en pr\u00e1ctica estas \ud83d\udc466 medidas si asaltan tu vivienda","breadcrumb":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/robo-casa-vivienda-cobertura-seguro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/"},{"@type":"ListItem","position":2,"name":"Seguridad","item":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/seguridad\/"},{"@type":"ListItem","position":3,"name":"\u00bfC\u00f3mo debes actuar si sufres un robo en casa?"}]},{"@type":"WebSite","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#website","url":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/","name":"Tu Asesor de Hogar","description":"Blog de Hogar de GENERALI","publisher":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#organization","name":"Tu Asesor de Hogar","url":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/logo\/image\/","url":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2021\/04\/generali.png","contentUrl":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2021\/04\/generali.png","width":100,"height":81,"caption":"Tu Asesor de Hogar"},"image":{"@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/person\/b3e3621e80b273ef3366c6dc945ab47e","name":"Equipo GENERALI","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/#\/schema\/person\/image\/","url":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2020\/11\/equipo_generali-150x150.jpg","contentUrl":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-content\/uploads\/2020\/11\/equipo_generali-150x150.jpg","caption":"Equipo GENERALI"},"description":"El equipo de Tu Asesor Hogar est\u00e1 compuesto por especialistas en la seguridad, el bricolaje y ahorro en el hogar, as\u00ed como profesionales t\u00e9cnicos de los seguros de hogar. Te ayudamos a que tengas una vida m\u00e1s segura y tranquila y te ofrecemos contenido \u00fatil para tu d\u00eda a d\u00eda.","url":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/author\/generali_asesor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/posts\/5373"}],"collection":[{"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/comments?post=5373"}],"version-history":[{"count":4,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/posts\/5373\/revisions"}],"predecessor-version":[{"id":5584,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/posts\/5373\/revisions\/5584"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/media\/5372"}],"wp:attachment":[{"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/media?parent=5373"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/categories?post=5373"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.generali.es\/blog\/tuasesorhogar\/wp-json\/wp\/v2\/tags?post=5373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}